{"id":14862,"date":"2026-06-11T17:10:39","date_gmt":"2026-06-11T16:10:39","guid":{"rendered":"https:\/\/friendmade.studio\/cases\/orovivo\/"},"modified":"2026-07-10T12:53:38","modified_gmt":"2026-07-10T11:53:38","slug":"orovivo","status":"publish","type":"page","link":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/","title":{"rendered":"friendmade\u00ae Studio \u2014 OROVIVO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":16227,"parent":14830,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-14862","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>friendmade\u00ae Studio \u2014 OROVIVO<\/title>\n<meta name=\"description\" content=\"friendmade X OROVIVO \u2013 Strategischen Markenpositionierung inklusive Store Design, Brand Design System, Kampagnenentwicklung und Kommunikationsmittel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/friendmade.studio\/de\/cases\/orovivo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"friendmade\u00ae Studio \u2014 OROVIVO\" \/>\n<meta property=\"og:description\" content=\"friendmade X OROVIVO \u2013 Strategischen Markenpositionierung inklusive Store Design, Brand Design System, Kampagnenentwicklung und Kommunikationsmittel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/friendmade.studio\/de\/cases\/orovivo\/\" \/>\n<meta property=\"og:site_name\" content=\"friendmade\u00ae studio\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T11:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/orovivo-mixboard-1400x939.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"939\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/\",\"url\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/\",\"name\":\"friendmade\u00ae Studio \u2014 OROVIVO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/friendmade.studio\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/orovivo-mixboard.jpg\",\"datePublished\":\"2026-06-11T16:10:39+00:00\",\"dateModified\":\"2026-07-10T11:53:38+00:00\",\"description\":\"friendmade X OROVIVO \u2013 Strategischen Markenpositionierung inklusive Store Design, Brand Design System, Kampagnenentwicklung und Kommunikationsmittel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/friendmade.studio\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/orovivo-mixboard.jpg\",\"contentUrl\":\"https:\\\/\\\/friendmade.studio\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/orovivo-mixboard.jpg\",\"width\":5056,\"height\":3392},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/orovivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"friendmade\u00ae studio \u2013 Cases\",\"item\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/cases\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"friendmade\u00ae Studio \u2014 OROVIVO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/\",\"name\":\"friendmade\u00ae studio\",\"description\":\"Studio for\u00a0Contemporary Brand, Art &amp; Spaces\",\"publisher\":{\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/#organization\",\"name\":\"friendmade\u00ae GmbH\",\"url\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/friendmade.studio\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/friendmade_logo_black-2.png\",\"contentUrl\":\"https:\\\/\\\/friendmade.studio\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/friendmade_logo_black-2.png\",\"width\":1606,\"height\":271,\"caption\":\"friendmade\u00ae GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/friendmade.studio\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/friendmade\\\/\",\"https:\\\/\\\/instagram.com\\\/friendmade.studio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"friendmade\u00ae Studio \u2014 OROVIVO","description":"friendmade X OROVIVO \u2013 Strategischen Markenpositionierung inklusive Store Design, Brand Design System, Kampagnenentwicklung und Kommunikationsmittel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/","og_locale":"de_DE","og_type":"article","og_title":"friendmade\u00ae Studio \u2014 OROVIVO","og_description":"friendmade X OROVIVO \u2013 Strategischen Markenpositionierung inklusive Store Design, Brand Design System, Kampagnenentwicklung und Kommunikationsmittel.","og_url":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/","og_site_name":"friendmade\u00ae studio","article_modified_time":"2026-07-10T11:53:38+00:00","og_image":[{"width":1400,"height":939,"url":"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/orovivo-mixboard-1400x939.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/","url":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/","name":"friendmade\u00ae Studio \u2014 OROVIVO","isPartOf":{"@id":"https:\/\/friendmade.studio\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/#primaryimage"},"image":{"@id":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/#primaryimage"},"thumbnailUrl":"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/orovivo-mixboard.jpg","datePublished":"2026-06-11T16:10:39+00:00","dateModified":"2026-07-10T11:53:38+00:00","description":"friendmade X OROVIVO \u2013 Strategischen Markenpositionierung inklusive Store Design, Brand Design System, Kampagnenentwicklung und Kommunikationsmittel.","breadcrumb":{"@id":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/friendmade.studio\/de\/cases\/orovivo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/#primaryimage","url":"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/orovivo-mixboard.jpg","contentUrl":"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/orovivo-mixboard.jpg","width":5056,"height":3392},{"@type":"BreadcrumbList","@id":"https:\/\/friendmade.studio\/de\/cases\/orovivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/friendmade.studio\/de\/"},{"@type":"ListItem","position":2,"name":"friendmade\u00ae studio \u2013 Cases","item":"https:\/\/friendmade.studio\/de\/cases\/"},{"@type":"ListItem","position":3,"name":"friendmade\u00ae Studio \u2014 OROVIVO"}]},{"@type":"WebSite","@id":"https:\/\/friendmade.studio\/de\/#website","url":"https:\/\/friendmade.studio\/de\/","name":"friendmade\u00ae studio","description":"Studio for\u00a0Contemporary Brand, Art &amp; Spaces","publisher":{"@id":"https:\/\/friendmade.studio\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/friendmade.studio\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/friendmade.studio\/de\/#organization","name":"friendmade\u00ae GmbH","url":"https:\/\/friendmade.studio\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/friendmade.studio\/de\/#\/schema\/logo\/image\/","url":"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/friendmade_logo_black-2.png","contentUrl":"https:\/\/friendmade.studio\/web\/wp-content\/uploads\/2026\/07\/friendmade_logo_black-2.png","width":1606,"height":271,"caption":"friendmade\u00ae GmbH"},"image":{"@id":"https:\/\/friendmade.studio\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/friendmade\/","https:\/\/instagram.com\/friendmade.studio"]}]}},"_links":{"self":[{"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/pages\/14862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/comments?post=14862"}],"version-history":[{"count":0,"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/pages\/14862\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/pages\/14830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/media\/16227"}],"wp:attachment":[{"href":"https:\/\/friendmade.studio\/de\/wp-json\/wp\/v2\/media?parent=14862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}